{"id":31335,"date":"2022-02-08T13:58:01","date_gmt":"2022-02-08T12:58:01","guid":{"rendered":"https:\/\/papierblau.ch\/?post_type=product&#038;p=31335"},"modified":"2025-10-27T14:46:20","modified_gmt":"2025-10-27T13:46:20","slug":"sticker-duo-schmetterlinge","status":"publish","type":"product","link":"https:\/\/papierblau.ch\/en\/product\/sticker-duo-schmetterlinge\/","title":{"rendered":"Sticker-Duo Schmetterlinge \u2013 transparent"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;0px||||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.16&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; width=&#8220;100%&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_wc_cart_notice _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][\/et_pb_wc_cart_notice][et_pb_wc_breadcrumb breadcrumb_home_text=&#8220;Produkte&#8220; breadcrumb_home_url=&#8220;https:\/\/papierblau.ch\/produkt-kategorie\/produkte\/&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_wc_breadcrumb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_2,1_2&#8243; _builder_version=&#8220;4.16&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; width=&#8220;100%&#8220; custom_padding=&#8220;0px||||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_wc_images _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][\/et_pb_wc_images][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_wc_title _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][\/et_pb_wc_title][et_pb_wc_rating _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][\/et_pb_wc_rating][et_pb_wc_price _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][\/et_pb_wc_price][et_pb_wc_description _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][\/et_pb_wc_description][et_pb_wc_add_to_cart _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][\/et_pb_wc_add_to_cart][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.16&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; width=&#8220;100%&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_wc_tabs include_tabs=&#8220;description||reviews&#8220; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;] [\/et_pb_wc_tabs][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>Das k\u00f6nnte dir auch gefallen<\/h3>\n<p>[\/et_pb_text][et_pb_shop type=&#8220;product_category&#8220; posts_number=&#8220;3&#8243; include_categories=&#8220;125&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_shop][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Transparente Sticker zur Versch\u00f6nerung von hellen Oberfl\u00e4chen.<\/p>","protected":false},"featured_media":31338,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"Sticker mit transparentem Hintergrund.\r\n\r\nSchmetterlingsmotive gedruckt auf Vinyl. Eignen sich besonders zum Aufkleben auf hellem Untergrund.\r\n\r\n2 verschiedene Motive, je 3 St\u00fcck. Total 6 St\u00fcck.","_et_gb_content_width":""},"product_brand":[],"product_cat":[144,125,41],"product_tag":[],"class_list":{"0":"post-31335","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-produkte","7":"product_cat-motiv-sticker","8":"product_cat-stickers","10":"first","11":"instock","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sticker-Duo Schmetterlinge - transparent | Papierblau<\/title>\n<meta name=\"description\" content=\"Transparente Sticker mit Schmetterlingmotiven. Zwei verschiedene Motive, je 3 Sticker. Kostenloser Versand ab CHF 75.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/papierblau.ch\/en\/product\/sticker-duo-schmetterlinge\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sticker-Duo Schmetterlinge - transparent | Papierblau\" \/>\n<meta property=\"og:description\" content=\"Transparente Sticker mit Schmetterlingmotiven. Zwei verschiedene Motive, je 3 Sticker. Kostenloser Versand ab CHF 75.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/papierblau.ch\/en\/product\/sticker-duo-schmetterlinge\/\" \/>\n<meta property=\"og:site_name\" content=\"Papierblau\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/papierblau.ch\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-27T13:46:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/papierblau.ch\/wp-content\/uploads\/2022\/02\/sticker_duo_schmetterling_shopbild.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/papierblau.ch\\\/produkt\\\/sticker-duo-schmetterlinge\\\/\",\"url\":\"https:\\\/\\\/papierblau.ch\\\/produkt\\\/sticker-duo-schmetterlinge\\\/\",\"name\":\"Sticker-Duo Schmetterlinge - transparent | Papierblau\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/papierblau.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/papierblau.ch\\\/produkt\\\/sticker-duo-schmetterlinge\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/papierblau.ch\\\/produkt\\\/sticker-duo-schmetterlinge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/papierblau.ch\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/sticker_duo_schmetterling_shopbild.jpg\",\"datePublished\":\"2022-02-08T12:58:01+00:00\",\"dateModified\":\"2025-10-27T13:46:20+00:00\",\"description\":\"Transparente Sticker mit Schmetterlingmotiven. Zwei verschiedene Motive, je 3 Sticker. Kostenloser Versand ab CHF 75.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/papierblau.ch\\\/produkt\\\/sticker-duo-schmetterlinge\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/papierblau.ch\\\/produkt\\\/sticker-duo-schmetterlinge\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/papierblau.ch\\\/produkt\\\/sticker-duo-schmetterlinge\\\/#primaryimage\",\"url\":\"https:\\\/\\\/papierblau.ch\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/sticker_duo_schmetterling_shopbild.jpg\",\"contentUrl\":\"https:\\\/\\\/papierblau.ch\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/sticker_duo_schmetterling_shopbild.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/papierblau.ch\\\/produkt\\\/sticker-duo-schmetterlinge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/papierblau.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produkte\",\"item\":\"https:\\\/\\\/papierblau.ch\\\/produkte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sticker-Duo Schmetterlinge \u2013 transparent\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/papierblau.ch\\\/#website\",\"url\":\"https:\\\/\\\/papierblau.ch\\\/\",\"name\":\"Papierblau\",\"description\":\"Karten, Sticker und mehr\",\"publisher\":{\"@id\":\"https:\\\/\\\/papierblau.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/papierblau.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/papierblau.ch\\\/#organization\",\"name\":\"Papierblau\",\"url\":\"https:\\\/\\\/papierblau.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/papierblau.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/papierblau.ch\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-Logo_bild.png\",\"contentUrl\":\"https:\\\/\\\/papierblau.ch\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-Logo_bild.png\",\"width\":512,\"height\":512,\"caption\":\"Papierblau\"},\"image\":{\"@id\":\"https:\\\/\\\/papierblau.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/papierblau.ch\",\"https:\\\/\\\/instagram.com\\\/papierblau\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sticker-Duo Schmetterlinge - transparent | Papierblau","description":"Transparente Sticker mit Schmetterlingmotiven. Zwei verschiedene Motive, je 3 Sticker. Kostenloser Versand ab CHF 75.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/papierblau.ch\/en\/product\/sticker-duo-schmetterlinge\/","og_locale":"en_GB","og_type":"article","og_title":"Sticker-Duo Schmetterlinge - transparent | Papierblau","og_description":"Transparente Sticker mit Schmetterlingmotiven. Zwei verschiedene Motive, je 3 Sticker. Kostenloser Versand ab CHF 75.","og_url":"https:\/\/papierblau.ch\/en\/product\/sticker-duo-schmetterlinge\/","og_site_name":"Papierblau","article_publisher":"https:\/\/facebook.com\/papierblau.ch","article_modified_time":"2025-10-27T13:46:20+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/papierblau.ch\/wp-content\/uploads\/2022\/02\/sticker_duo_schmetterling_shopbild.jpg","type":"image\/jpeg"}],"twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/papierblau.ch\/produkt\/sticker-duo-schmetterlinge\/","url":"https:\/\/papierblau.ch\/produkt\/sticker-duo-schmetterlinge\/","name":"Sticker-Duo Schmetterlinge - transparent | Papierblau","isPartOf":{"@id":"https:\/\/papierblau.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/papierblau.ch\/produkt\/sticker-duo-schmetterlinge\/#primaryimage"},"image":{"@id":"https:\/\/papierblau.ch\/produkt\/sticker-duo-schmetterlinge\/#primaryimage"},"thumbnailUrl":"https:\/\/papierblau.ch\/wp-content\/uploads\/2022\/02\/sticker_duo_schmetterling_shopbild.jpg","datePublished":"2022-02-08T12:58:01+00:00","dateModified":"2025-10-27T13:46:20+00:00","description":"Transparente Sticker mit Schmetterlingmotiven. Zwei verschiedene Motive, je 3 Sticker. Kostenloser Versand ab CHF 75.","breadcrumb":{"@id":"https:\/\/papierblau.ch\/produkt\/sticker-duo-schmetterlinge\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/papierblau.ch\/produkt\/sticker-duo-schmetterlinge\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/papierblau.ch\/produkt\/sticker-duo-schmetterlinge\/#primaryimage","url":"https:\/\/papierblau.ch\/wp-content\/uploads\/2022\/02\/sticker_duo_schmetterling_shopbild.jpg","contentUrl":"https:\/\/papierblau.ch\/wp-content\/uploads\/2022\/02\/sticker_duo_schmetterling_shopbild.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/papierblau.ch\/produkt\/sticker-duo-schmetterlinge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/papierblau.ch\/"},{"@type":"ListItem","position":2,"name":"Produkte","item":"https:\/\/papierblau.ch\/produkte\/"},{"@type":"ListItem","position":3,"name":"Sticker-Duo Schmetterlinge \u2013 transparent"}]},{"@type":"WebSite","@id":"https:\/\/papierblau.ch\/#website","url":"https:\/\/papierblau.ch\/","name":"Papierblau","description":"Karten, Sticker und mehr","publisher":{"@id":"https:\/\/papierblau.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/papierblau.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/papierblau.ch\/#organization","name":"Papierblau","url":"https:\/\/papierblau.ch\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/papierblau.ch\/#\/schema\/logo\/image\/","url":"https:\/\/papierblau.ch\/wp-content\/uploads\/2020\/05\/cropped-Logo_bild.png","contentUrl":"https:\/\/papierblau.ch\/wp-content\/uploads\/2020\/05\/cropped-Logo_bild.png","width":512,"height":512,"caption":"Papierblau"},"image":{"@id":"https:\/\/papierblau.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/papierblau.ch","https:\/\/instagram.com\/papierblau"]}]}},"_links":{"self":[{"href":"https:\/\/papierblau.ch\/en\/wp-json\/wp\/v2\/product\/31335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/papierblau.ch\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/papierblau.ch\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/papierblau.ch\/en\/wp-json\/wp\/v2\/comments?post=31335"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/papierblau.ch\/en\/wp-json\/wp\/v2\/media\/31338"}],"wp:attachment":[{"href":"https:\/\/papierblau.ch\/en\/wp-json\/wp\/v2\/media?parent=31335"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/papierblau.ch\/en\/wp-json\/wp\/v2\/product_brand?post=31335"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/papierblau.ch\/en\/wp-json\/wp\/v2\/product_cat?post=31335"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/papierblau.ch\/en\/wp-json\/wp\/v2\/product_tag?post=31335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}