{"id":230,"count":8,"description":"Notizen machen doch gleich mehr Spass auf einem ansprechenden Notizblock oder in einem h\u00fcbschen Notizbuch.","link":"https:\/\/papierblau.ch\/en\/product-category\/notizen\/","name":"Notes","slug":"notizen","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":5,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Notizb\u00fccher und Notizbl\u00f6cke | Papierblau<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/papierblau.ch\/en\/product-category\/notizen\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Notizb\u00fccher und Notizbl\u00f6cke | Papierblau\" \/>\n<meta property=\"og:description\" content=\"Notizen machen doch gleich mehr Spass auf einem ansprechenden Notizblock oder in einem h\u00fcbschen Notizbuch.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/papierblau.ch\/en\/product-category\/notizen\/\" \/>\n<meta property=\"og:site_name\" content=\"Papierblau\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/papierblau.ch\\\/produkt-kategorie\\\/notizen\\\/\",\"url\":\"https:\\\/\\\/papierblau.ch\\\/produkt-kategorie\\\/notizen\\\/\",\"name\":\"Notizb\u00fccher und Notizbl\u00f6cke | Papierblau\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/papierblau.ch\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/papierblau.ch\\\/produkt-kategorie\\\/notizen\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/papierblau.ch\\\/produkt-kategorie\\\/notizen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/papierblau.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notizen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/papierblau.ch\\\/#website\",\"url\":\"https:\\\/\\\/papierblau.ch\\\/\",\"name\":\"Papierblau\",\"description\":\"Karten, Sticker und mehr\",\"publisher\":{\"@id\":\"https:\\\/\\\/papierblau.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/papierblau.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/papierblau.ch\\\/#organization\",\"name\":\"Papierblau\",\"url\":\"https:\\\/\\\/papierblau.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/papierblau.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/papierblau.ch\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-Logo_bild.png\",\"contentUrl\":\"https:\\\/\\\/papierblau.ch\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/cropped-Logo_bild.png\",\"width\":512,\"height\":512,\"caption\":\"Papierblau\"},\"image\":{\"@id\":\"https:\\\/\\\/papierblau.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/papierblau.ch\",\"https:\\\/\\\/instagram.com\\\/papierblau\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Notizb\u00fccher und Notizbl\u00f6cke | Papierblau","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/papierblau.ch\/en\/product-category\/notizen\/","og_locale":"en_GB","og_type":"article","og_title":"Notizb\u00fccher und Notizbl\u00f6cke | Papierblau","og_description":"Notizen machen doch gleich mehr Spass auf einem ansprechenden Notizblock oder in einem h\u00fcbschen Notizbuch.","og_url":"https:\/\/papierblau.ch\/en\/product-category\/notizen\/","og_site_name":"Papierblau","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/papierblau.ch\/produkt-kategorie\/notizen\/","url":"https:\/\/papierblau.ch\/produkt-kategorie\/notizen\/","name":"Notizb\u00fccher und Notizbl\u00f6cke | Papierblau","isPartOf":{"@id":"https:\/\/papierblau.ch\/#website"},"breadcrumb":{"@id":"https:\/\/papierblau.ch\/produkt-kategorie\/notizen\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/papierblau.ch\/produkt-kategorie\/notizen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/papierblau.ch\/"},{"@type":"ListItem","position":2,"name":"Notizen"}]},{"@type":"WebSite","@id":"https:\/\/papierblau.ch\/#website","url":"https:\/\/papierblau.ch\/","name":"Papierblau","description":"Karten, Sticker und mehr","publisher":{"@id":"https:\/\/papierblau.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/papierblau.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/papierblau.ch\/#organization","name":"Papierblau","url":"https:\/\/papierblau.ch\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/papierblau.ch\/#\/schema\/logo\/image\/","url":"https:\/\/papierblau.ch\/wp-content\/uploads\/2020\/05\/cropped-Logo_bild.png","contentUrl":"https:\/\/papierblau.ch\/wp-content\/uploads\/2020\/05\/cropped-Logo_bild.png","width":512,"height":512,"caption":"Papierblau"},"image":{"@id":"https:\/\/papierblau.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/papierblau.ch","https:\/\/instagram.com\/papierblau"]}]}},"_links":{"self":[{"href":"https:\/\/papierblau.ch\/en\/wp-json\/wp\/v2\/product_cat\/230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/papierblau.ch\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/papierblau.ch\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/papierblau.ch\/en\/wp-json\/wp\/v2\/product?product_cat=230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}